{"id":13883,"date":"2023-08-17T16:09:09","date_gmt":"2023-08-17T16:09:09","guid":{"rendered":"https:\/\/urbanyouthgames.org\/?p=13883"},"modified":"2023-10-31T13:50:25","modified_gmt":"2023-10-31T13:50:25","slug":"stage-project-management-sport-education","status":"publish","type":"post","link":"https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/","title":{"rendered":"Stage &#8211; Project Management (Sport &#038; Education)"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><a>Constitu\u00e9s sous la forme d\u2019une ASBL, les&nbsp;<\/a><a href=\"about:blank\"><strong>Urban Youth Games<\/strong><\/a>&nbsp;sont un mouvement qui&nbsp;<strong>vise \u00e0 inspirer les jeunes et \u00e0 favoriser l\u2019inclusion sociale et le mieux \u00ab vivre-ensemble \u00bb<\/strong>&nbsp;au travers de rencontres sportives.&nbsp;<\/p>\n\n\n\n<p>Au-del\u00e0 de l\u2019organisation d&#8217;\u00e9v\u00e9nements sportifs d\u2019ampleur, les Urban Youth Games ont \u00e9galement cr\u00e9\u00e9 un parcours d\u2019inclusion sociale. Il s\u2019articule au travers de manuels de jeux inclusifs, appel\u00e9s \u00ab&nbsp;Inclusive Playbooks&nbsp;\u00bb, \u00e0 destination des professeurs d\u2019\u00e9ducation physique, et de \u00ab&nbsp;Challenges&nbsp;\u00bb entre des \u00e9coles primaires de l\u2019Enseignement g\u00e9n\u00e9ral et sp\u00e9cialis\u00e9.&nbsp;<\/p>\n\n\n\n<p>Nous travaillons en \u00e9troite collaboration avec Team Belgium, Paralympic Team Belgium, Special Olympics Belgium, les f\u00e9d\u00e9rations et ligues sportives, des clubs locaux, des experts dans le domaine de l&#8217;Education et de l&#8217;Inclusion, et avec la VUB pour mesurer l\u2019impact de nos actions.&nbsp;<\/p>\n\n\n\n<p>Voici l\u2019aftermovie d&#8217;un de nos \u00e9v\u00e9nements :&nbsp;<a href=\"https:\/\/youtu.be\/goeuFTWB374\">\u00c9dition nationale 2023 &#8211; Urban Youth Games<\/a><\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong><u>Proposition de stage<\/u><\/strong><\/p>\n\n\n\n<p>Pour soutenir le d\u00e9veloppement de notre programme annuel, les Urban Youth Games recherchent un.e&nbsp;<strong>stagiaire en Project Management Sport &amp; \u00c9ducation<\/strong>.<\/p>\n\n\n\n<p>&#8211; <strong>Vous aidez \u00e0 la planification, pr\u00e9paration et coordination&nbsp;<\/strong>op\u00e9rationnelle<strong>&nbsp;<\/strong>de la mise en place des \u00e9v\u00e9nements Urban Youth Games (scope&nbsp;: Bxl\/Flandre\/Wallonie) en collaboration avec la Project Manager Sports &amp; Education et l\u2019Event Manager.<\/p>\n\n\n\n<p>&#8211; <strong>Vous aidez \u00e0 am\u00e9liorer<\/strong>&nbsp;le d\u00e9roulement des \u00e9v\u00e9nements&nbsp;: gestion des plannings pour les \u00e9coles, des coachs et autres partenaires\/parties prenantes. &#8211;<\/p>\n\n\n\n<p><strong> &#8211; Vous d\u00e9veloppez la relation avec nos interlocuteurs&nbsp;:&nbsp;<\/strong>les \u00e9coles, f\u00e9d\u00e9rations et clubs sportifs pour l\u2019inscription des \u00e9coles et&nbsp;<strong>veillez \u00e0<\/strong>&nbsp;la bonne mise en place et coordination des activit\u00e9s sportives. En m\u00eame temps, vous \u00eates la voix et l\u2019ambassadeur.rice des UYG.&nbsp;<\/p>\n\n\n\n<p>&#8211; <strong>Vous coordonnez, inspirez et encouragez&nbsp;<\/strong>les b\u00e9n\u00e9voles, clubs sportifs, f\u00e9d\u00e9rations, \u2026 \u00e0 encadrer qualitativement les enfants lors de nos faire des \u00e9v\u00e9nements.<\/p>\n\n\n\n<p>&#8211; <strong>Vous collaborez<\/strong>&nbsp;avec l\u2019Event Manager et&nbsp;<strong>aidez<\/strong>&nbsp;avec l\u2019organisation op\u00e9rationnelle de l\u2019\u00e9v\u00e9nement, comme le montage et d\u00e9montage.<\/p>\n\n\n\n<p>&#8211;&nbsp;Vous vous investissez dans le d\u00e9veloppement du Parcours d\u2019Inclusion Sociale (playbooks et Challenges) et en&nbsp;<strong>faites la promotion<\/strong>&nbsp;aupr\u00e8s des professeurs d\u2019\u00e9ducation physique.&nbsp;<\/p>\n\n\n\n<p>&#8211; <strong>Vous collectez des donn\u00e9es&nbsp;<\/strong>en r\u00e9alisant des enqu\u00eates et en discutant avec nos partenaires, les utilisateurs des playbooks et les participants aux \u00e9v\u00e9nements.&nbsp;<\/p>\n\n\n\n<p>&#8211; <strong>Vous d\u00e9veloppez et am\u00e9liorez<\/strong>&nbsp;les manuels de jeu inclusifs (playbooks) et suivez leur utilisation avec les diff\u00e9rentes \u00e9coles. Vous apportez des am\u00e9liorations en fonction des commentaires des utilisateurs.<\/p>\n\n\n\n<p>&#8211; <strong>Vous proposez des id\u00e9es innovantes&nbsp;<\/strong>tant<strong>&nbsp;<\/strong>sur les aspects li\u00e9s \u00e0 l\u2019\u00e9v\u00e9nementiel (nouvelles tendances) que sur les moyens de mettre en avant l\u2019inclusion lors des \u00e9v\u00e9nements (en collaboration avec l\u2019\u00e9quipe).<\/p>\n\n\n\n<p>&#8211; <strong>Vous menez&nbsp;<\/strong>des projets et autres t\u00e2ches ad hoc.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>En r\u00e9sum\u00e9,&nbsp;<\/strong>vous allez :&nbsp;<\/p>\n\n\n\n<p>&#8211; Contribuer \u00e0 mettre sur pied des \u00e9v\u00e9nements d\u2019ampleur sportifs et inclusifs (par ann\u00e9e, cela repr\u00e9sente : 7 \u00e9v\u00e9nements, +\/- 10.000 participants, +\/- 500 b\u00e9n\u00e9voles et +\/- 75 clubs et f\u00e9d\u00e9rations sportives rien qu\u2019en 2023).<\/p>\n\n\n\n<p>&#8211; Aider \u00e0 la gestion des inscriptions et la recherche de coachs sportifs.<\/p>\n\n\n\n<p>&#8211; Contribuer \u00e0 l&#8217;organisation des Urban Youth Games \u00e0 Seine-Saint-Denis (Paris) en amont des Jeux Olympiques et Paralympiques de Paris 2024.<\/p>\n\n\n\n<p>&#8211; G\u00e9rer nos parties prenantes : \u00e9coles, clubs locaux, f\u00e9d\u00e9rations, partenaires, fournisseurs, &#8230;&nbsp;<\/p>\n\n\n\n<p>&#8211; Accueillir les \u00e9coles et les clubs\/f\u00e9d\u00e9rations sportives lors des \u00e9v\u00e9nements sportifs.<\/p>\n\n\n\n<p>&#8211; D\u00e9velopper des exercices sportifs pour nos Playbooks<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong><u>Qui recherchons-nous ?&nbsp;<\/u><\/strong><\/p>\n\n\n\n<p>Vous \u00eates passionn\u00e9.e par les \u00e9v\u00e9nements, le sport, l&#8217;inclusion, les jeunes et le monde associatif ? Vous avez envie de vous faire une premi\u00e8re exp\u00e9rience dans le secteur de l\u2019\u00e9v\u00e9nementiel sportif ? Vous \u00eates orient\u00e9.e vers l&#8217;action et vous aimez assurer le suivi des projets ? Vous aimez nouer de nouveaux contacts et interagir avec un large panel de parties prenantes ? Vous pourrez alors utiliser vos talents afin de cr\u00e9er un impact durable.&nbsp;<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong><u>Les besoins du poste\/stage<\/u><\/strong><strong>&nbsp;:<\/strong><\/p>\n\n\n\n<p>&#8211; Une bonne connaissance du fran\u00e7ais et du n\u00e9erlandais est n\u00e9cessaire car vous allez cr\u00e9er et entretenir des contacts en fran\u00e7ais, tant \u00e0 l&#8217;oral qu&#8217;\u00e0 l&#8217;\u00e9crit.<\/p>\n\n\n\n<p>&#8211; Vous avez une bonne compr\u00e9hension et ma\u00eetrise de l&#8217;anglais car vous serez en contact avec des partenaires ou des coll\u00e8gues qui parlent anglais.<\/p>\n\n\n\n<p>&#8211; Vous \u00eates capable de d\u00e9velopper des (nouveaux) projets de A \u00e0 Z.<\/p>\n\n\n\n<p>&#8211; Vous \u00eates pragmatique, ouvert.e d\u2019esprit, sociable et aimez nouer de nouveaux contacts.<\/p>\n\n\n\n<p>&#8211; Vous avez une sensibilit\u00e9 pour le monde du sport.&nbsp;<\/p>\n\n\n\n<p>&#8211; Vous avez une exp\u00e9rience (de tout type) dans la gestion de projets ou d&#8217;\u00e9v\u00e9nements est un plus, car il s&#8217;agit d&#8217;une partie importante du travail.<\/p>\n\n\n\n<p>&#8211; Vous prenez en charge vos projets, en travaillant de mani\u00e8re ind\u00e9pendante et structur\u00e9e.<\/p>\n\n\n\n<p>&#8211; Vous \u00eates r\u00e9sistant.e au stress et flexible ; la pr\u00e9paration d&#8217;un \u00e9v\u00e9nement peut \u00eatre intense et stressante.<\/p>\n\n\n\n<p>Nous recrutons sur la base des comp\u00e9tences et des talents, sans distinction d&#8217;\u00e2ge, de sexe, d&#8217;identit\u00e9 de genre, d&#8217;origines ou de handicap.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong><u>Que proposons-nous<\/u><\/strong><strong>&nbsp;?<\/strong><\/p>\n\n\n\n<p>Vous ferez partie d&#8217;une \u00e9quipe de coll\u00e8gues hyper motiv\u00e9s, ayant de l&#8217;exp\u00e9rience dans le secteur associatif, de l\u2019\u00e9v\u00e9nementiel et du sport, afin de d\u00e9velopper un projet en pleine croissance et qui a du sens&nbsp;:&nbsp;<\/p>\n\n\n\n<p>&#8211; Un&nbsp;<strong>stage vari\u00e9 et stimulant&nbsp;<\/strong>qui contribue positivement \u00e0 des d\u00e9fis soci\u00e9taux.&nbsp;<\/p>\n\n\n\n<p>&#8211; <strong> Un environnement dynamique au c\u0153ur du quartier europ\u00e9en<\/strong>, pr\u00e8s de l\u2019arr\u00eat de m\u00e9tro Arts-Loi. Nos bureaux se trouvent \u00e0 quelques pas des gares de Bruxelles-Centrale, Bruxelles-Schuman et Bruxelles-Luxembourg (jusqu\u2019en d\u00e9cembre 2023). Apr\u00e8s nous d\u00e9m\u00e9nagerons \u00e0 Laeken d\u00e8s janvier 2024, dans les bureaux du Comit\u00e9 Olympique et Interf\u00e9d\u00e9ral Belge (Team Belgium).&nbsp;<\/p>\n\n\n\n<p>&#8211; Les frais de transport sont rembours\u00e9s par l&#8217;employeur.&nbsp;<\/p>\n\n\n\n<p>&#8211; Il existe&nbsp;<strong>une possibilit\u00e9 de t\u00e9l\u00e9travail&nbsp;<\/strong>(nombre de jours\/semaine \u00e0 d\u00e9finir ensemble).&nbsp;<\/p>\n\n\n\n<p>&#8211; <strong>Opportunit\u00e9 de stage&nbsp;<\/strong>\u00e0 partir du 1 septembre 2023 ou \u00e0 partir du 1 f\u00e9vrier 2024.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong><u>Vous souhaitez rejoindre notre \u00e9quipe<\/u>&nbsp;?<\/strong><\/p>\n\n\n\n<p>Proposez votre candidature en envoyant votre CV et votre lettre de motivation \u00e0&nbsp;<a href=\"about:blank\">info@urbanyouthgames.org<\/a>. Vous pouvez \u00e9galement nous joindre par t\u00e9l\u00e9phone au 0498\/10.67.02 pour toute question. Les candidat.e.s recevront un retour d&#8217;information end\u00e9ans les 15 jours. Les candidat.e.s s\u00e9lectionn\u00e9.e.s recevront une invitation pour un entretien. Il sera fix\u00e9 en fonction des disponibilit\u00e9s du\/de la candidat.e et aura lieu pendant la journ\u00e9e \u00e0 partir de la semaine du 21 ao\u00fbt 2023&nbsp;(dans nos bureaux \u00e0 Bruxelles ou en visioconf\u00e9rence).<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong><u>Informations compl\u00e9mentaires<\/u><\/strong><\/p>\n\n\n\n<p><em>Notre mission et feuille de route<\/em><\/p>\n\n\n\n<p>D\u2019envergure nationale, les UYG mettent en place une feuille de route ambitieuse tout au long de l\u2019ann\u00e9e \u00e0 l\u2019attention des jeunes de 5<sup>\u00e8me<\/sup>&nbsp;et 6<sup>\u00e8me<\/sup>&nbsp;primaire (+\/- de 10 \u00e0 12 ans). Elle se d\u00e9cline en deux axes strat\u00e9giques :<\/p>\n\n\n\n<ol class=\"wp-block-list\" type=\"I\">\n<li>le d\u00e9veloppement d\u2019outils p\u00e9dagogiques dans les \u00e9coles primaires, appel\u00e9s \u00ab Inclusive Playbooks \u00bb, qui sont cr\u00e9\u00e9s en collaboration avec les F\u00e9d\u00e9rations sportives, des experts en Inclusion et des acteurs cl\u00e9s de l\u2019Enseignement ;<br><\/li>\n\n\n\n<li>des \u00e9v\u00e9nements d\u2019ampleur \u00e0 diff\u00e9rentes \u00e9chelles (locaux, provinciaux, r\u00e9gionaux, national et europ\u00e9en)&nbsp;;<\/li>\n<\/ol>\n\n\n\n<p>En mettant le sport au service de l\u2019inclusion, les UYG ont d\u00e9velopp\u00e9 un mod\u00e8le qui permet \u00e0 chaque jeune de devenir acteur de l\u2019activit\u00e9 sportive, de s\u2019ouvrir, d\u2019\u00e9changer et enfin de s\u2019\u00e9panouir. En cassant les barri\u00e8res sociales et culturelles par le sport, nous avons l\u2019opportunit\u00e9 de les sensibiliser aux d\u00e9fis soci\u00e9taux de demain.<\/p>\n\n\n\n<p><em>Notre vision<\/em><\/p>\n\n\n\n<p>Devenir le mouvement de r\u00e9f\u00e9rence qui rassemble tous les jeunes sans distinction de genre, d\u2019handicap, de religion, d\u2019orientation sexuelle, de langue, etc.<\/p>\n\n\n\n<p>En d\u2019autres termes, rassembler les mouvements \u00ab&nbsp;Olympique \u2013 Paralympique \u2013 Special Olympics&nbsp;\u00bb en seul et m\u00eame mouvement pour la jeunesse (\/\/ sport pour tous).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Constitu\u00e9s sous la forme d\u2019une ASBL, les&nbsp;Urban Youth Games&nbsp;sont un mouvement qui&nbsp;vise \u00e0 inspirer les jeunes et \u00e0 favoriser l\u2019inclusion sociale et le mieux \u00ab vivre-ensemble \u00bb&nbsp;au travers de rencontres sportives.&nbsp; Au-del\u00e0 de l\u2019organisation d&#8217;\u00e9v\u00e9nements sportifs d\u2019ampleur, les Urban Youth [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":13968,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[109,98],"tags":[],"class_list":["post-13883","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Stage - Project Management (Sport &amp; Education) - Urban Youth Games<\/title>\n<meta name=\"description\" content=\"Inspirer l\u2019excellence et apporter de l\u2019espoir \u00e0 chaque enfant, dans chaque quartier.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stage - Project Management (Sport &amp; Education) - Urban Youth Games\" \/>\n<meta property=\"og:description\" content=\"Inspirer l\u2019excellence et apporter de l\u2019espoir \u00e0 chaque enfant, dans chaque quartier.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/\" \/>\n<meta property=\"og:site_name\" content=\"Urban Youth Games\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-17T16:09:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-31T13:50:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/urbanyouthgames.org\/wp-content\/uploads\/2023\/08\/2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"UYG team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"UYG team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/\"},\"author\":{\"name\":\"UYG team\",\"@id\":\"https:\/\/urbanyouthgames.org\/fr\/#\/schema\/person\/492182992a419770d420462ca2b48f4f\"},\"headline\":\"Stage &#8211; Project Management (Sport &#038; Education)\",\"datePublished\":\"2023-08-17T16:09:09+00:00\",\"dateModified\":\"2023-10-31T13:50:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/\"},\"wordCount\":1416,\"publisher\":{\"@id\":\"https:\/\/urbanyouthgames.org\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/urbanyouthgames.org\/wp-content\/uploads\/2023\/08\/2.png\",\"articleSection\":[\"News\",\"Uncategorized\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/\",\"url\":\"https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/\",\"name\":\"Stage - Project Management (Sport & Education) - Urban Youth Games\",\"isPartOf\":{\"@id\":\"https:\/\/urbanyouthgames.org\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/urbanyouthgames.org\/wp-content\/uploads\/2023\/08\/2.png\",\"datePublished\":\"2023-08-17T16:09:09+00:00\",\"dateModified\":\"2023-10-31T13:50:25+00:00\",\"description\":\"Inspirer l\u2019excellence et apporter de l\u2019espoir \u00e0 chaque enfant, dans chaque quartier.\",\"breadcrumb\":{\"@id\":\"https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/#primaryimage\",\"url\":\"https:\/\/urbanyouthgames.org\/wp-content\/uploads\/2023\/08\/2.png\",\"contentUrl\":\"https:\/\/urbanyouthgames.org\/wp-content\/uploads\/2023\/08\/2.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/urbanyouthgames.org\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stage &#8211; Project Management (Sport &#038; Education)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/urbanyouthgames.org\/fr\/#website\",\"url\":\"https:\/\/urbanyouthgames.org\/fr\/\",\"name\":\"Urban Youth Games\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/urbanyouthgames.org\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/urbanyouthgames.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/urbanyouthgames.org\/fr\/#organization\",\"name\":\"Urban Youth Games\",\"url\":\"https:\/\/urbanyouthgames.org\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/urbanyouthgames.org\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/urbanyouthgames.org\/wp-content\/uploads\/2021\/04\/UYG_LOGO.svg\",\"contentUrl\":\"https:\/\/urbanyouthgames.org\/wp-content\/uploads\/2021\/04\/UYG_LOGO.svg\",\"width\":150,\"height\":100,\"caption\":\"Urban Youth Games\"},\"image\":{\"@id\":\"https:\/\/urbanyouthgames.org\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/urbanyouthgames.org\/fr\/#\/schema\/person\/492182992a419770d420462ca2b48f4f\",\"name\":\"UYG team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/urbanyouthgames.org\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a448632e969fdd3ee99d06409e05bd38?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a448632e969fdd3ee99d06409e05bd38?s=96&d=mm&r=g\",\"caption\":\"UYG team\"},\"url\":\"https:\/\/urbanyouthgames.org\/fr\/author\/uyg-editor\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stage - Project Management (Sport & Education) - Urban Youth Games","description":"Inspirer l\u2019excellence et apporter de l\u2019espoir \u00e0 chaque enfant, dans chaque quartier.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/","og_locale":"fr_FR","og_type":"article","og_title":"Stage - Project Management (Sport & Education) - Urban Youth Games","og_description":"Inspirer l\u2019excellence et apporter de l\u2019espoir \u00e0 chaque enfant, dans chaque quartier.","og_url":"https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/","og_site_name":"Urban Youth Games","article_published_time":"2023-08-17T16:09:09+00:00","article_modified_time":"2023-10-31T13:50:25+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/urbanyouthgames.org\/wp-content\/uploads\/2023\/08\/2.png","type":"image\/png"}],"author":"UYG team","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"UYG team","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/#article","isPartOf":{"@id":"https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/"},"author":{"name":"UYG team","@id":"https:\/\/urbanyouthgames.org\/fr\/#\/schema\/person\/492182992a419770d420462ca2b48f4f"},"headline":"Stage &#8211; Project Management (Sport &#038; Education)","datePublished":"2023-08-17T16:09:09+00:00","dateModified":"2023-10-31T13:50:25+00:00","mainEntityOfPage":{"@id":"https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/"},"wordCount":1416,"publisher":{"@id":"https:\/\/urbanyouthgames.org\/fr\/#organization"},"image":{"@id":"https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/#primaryimage"},"thumbnailUrl":"https:\/\/urbanyouthgames.org\/wp-content\/uploads\/2023\/08\/2.png","articleSection":["News","Uncategorized"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/","url":"https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/","name":"Stage - Project Management (Sport & Education) - Urban Youth Games","isPartOf":{"@id":"https:\/\/urbanyouthgames.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/#primaryimage"},"image":{"@id":"https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/#primaryimage"},"thumbnailUrl":"https:\/\/urbanyouthgames.org\/wp-content\/uploads\/2023\/08\/2.png","datePublished":"2023-08-17T16:09:09+00:00","dateModified":"2023-10-31T13:50:25+00:00","description":"Inspirer l\u2019excellence et apporter de l\u2019espoir \u00e0 chaque enfant, dans chaque quartier.","breadcrumb":{"@id":"https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/#primaryimage","url":"https:\/\/urbanyouthgames.org\/wp-content\/uploads\/2023\/08\/2.png","contentUrl":"https:\/\/urbanyouthgames.org\/wp-content\/uploads\/2023\/08\/2.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/urbanyouthgames.org\/fr\/stage-project-management-sport-education\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/urbanyouthgames.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Stage &#8211; Project Management (Sport &#038; Education)"}]},{"@type":"WebSite","@id":"https:\/\/urbanyouthgames.org\/fr\/#website","url":"https:\/\/urbanyouthgames.org\/fr\/","name":"Urban Youth Games","description":"","publisher":{"@id":"https:\/\/urbanyouthgames.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/urbanyouthgames.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/urbanyouthgames.org\/fr\/#organization","name":"Urban Youth Games","url":"https:\/\/urbanyouthgames.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/urbanyouthgames.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/urbanyouthgames.org\/wp-content\/uploads\/2021\/04\/UYG_LOGO.svg","contentUrl":"https:\/\/urbanyouthgames.org\/wp-content\/uploads\/2021\/04\/UYG_LOGO.svg","width":150,"height":100,"caption":"Urban Youth Games"},"image":{"@id":"https:\/\/urbanyouthgames.org\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/urbanyouthgames.org\/fr\/#\/schema\/person\/492182992a419770d420462ca2b48f4f","name":"UYG team","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/urbanyouthgames.org\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a448632e969fdd3ee99d06409e05bd38?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a448632e969fdd3ee99d06409e05bd38?s=96&d=mm&r=g","caption":"UYG team"},"url":"https:\/\/urbanyouthgames.org\/fr\/author\/uyg-editor\/"}]}},"_links":{"self":[{"href":"https:\/\/urbanyouthgames.org\/fr\/wp-json\/wp\/v2\/posts\/13883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/urbanyouthgames.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/urbanyouthgames.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/urbanyouthgames.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/urbanyouthgames.org\/fr\/wp-json\/wp\/v2\/comments?post=13883"}],"version-history":[{"count":3,"href":"https:\/\/urbanyouthgames.org\/fr\/wp-json\/wp\/v2\/posts\/13883\/revisions"}],"predecessor-version":[{"id":14021,"href":"https:\/\/urbanyouthgames.org\/fr\/wp-json\/wp\/v2\/posts\/13883\/revisions\/14021"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/urbanyouthgames.org\/fr\/wp-json\/wp\/v2\/media\/13968"}],"wp:attachment":[{"href":"https:\/\/urbanyouthgames.org\/fr\/wp-json\/wp\/v2\/media?parent=13883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urbanyouthgames.org\/fr\/wp-json\/wp\/v2\/categories?post=13883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urbanyouthgames.org\/fr\/wp-json\/wp\/v2\/tags?post=13883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}